{"id":808,"date":"2022-02-18T07:04:52","date_gmt":"2022-02-18T13:04:52","guid":{"rendered":"https:\/\/litoralatlanticohd.net\/?p=808"},"modified":"2022-02-18T07:04:54","modified_gmt":"2022-02-18T13:04:54","slug":"todo-listo-para-la-maraton-21-k-en-la-ciudad-puerto-de-la-ceiba","status":"publish","type":"post","link":"https:\/\/litoralatlanticohd.net\/index.php\/2022\/02\/18\/todo-listo-para-la-maraton-21-k-en-la-ciudad-puerto-de-la-ceiba\/","title":{"rendered":"Todo listo para la marat\u00f3n 21 K, en la ciudad puerto de La Ceiba.\u00a0\u00a0"},"content":{"rendered":"\n<p>La Ceiba, Atl\u00e1ntida&nbsp;<\/p>\n\n\n\n<p>Todo se encuentra listo para la marat\u00f3n 21K, seg\u00fan lo ha dicho en entrevista a Canal Litoral Atl\u00e1ntico,&nbsp;&nbsp;el Abogado Fernando Midence, Presidente del Centro Regional del Litoral Atl\u00e1ntico, CRILA<\/p>\n\n\n\n<p>Midence ha manifestado que la poblaci\u00f3n ha respondido a dicha actividad, la cual se llevar\u00e1 a cabo el pr\u00f3ximo domingo 20 de febrero, contando con la participaci\u00f3n de atletas locales, nacionales e internacionales.&nbsp;<\/p>\n\n\n\n<p>Esta actividad est\u00e1 siendo patrocinada por DOLE, y ser\u00e1 en beneficio tanto de CRILA, como la Fundaci\u00f3n Pro C\u00e1ncer La Ceiba, ambas instituciones de beneficencia que han dado muchos beneficios a la poblaci\u00f3n del litoral atl\u00e1ntico, en especial de la ciudad puerto de La Ceiba.<\/p>\n\n\n\n<p>La carrera, ser\u00e1 no solo de 21k, habr\u00e1 oportunidad para las personas que deseen competir en 5, 10 y 21 k.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ceiba, Atl\u00e1ntida&nbsp; Todo se encuentra listo para la marat\u00f3n 21K, seg\u00fan lo ha dicho en entrevista a Canal Litoral Atl\u00e1ntico,&nbsp;&nbsp;el Abogado Fernando Midence, Presidente del Centro Regional del Litoral Atl\u00e1ntico, CRILA Midence ha manifestado que la poblaci\u00f3n ha respondido a dicha actividad, la cual se llevar\u00e1 a cabo el pr\u00f3ximo domingo 20 de febrero, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false},"categories":[1],"tags":[177],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/posts\/808"}],"collection":[{"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/comments?post=808"}],"version-history":[{"count":1,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/posts\/808\/revisions"}],"predecessor-version":[{"id":810,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/posts\/808\/revisions\/810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/media\/809"}],"wp:attachment":[{"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/media?parent=808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/categories?post=808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/litoralatlanticohd.net\/index.php\/wp-json\/wp\/v2\/tags?post=808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}